{"id":5016,"date":"2025-10-18T18:16:49","date_gmt":"2025-10-18T18:16:49","guid":{"rendered":"https:\/\/dinaleo.com.ar\/sitio\/?post_type=product&#038;p=5016"},"modified":"2025-10-24T14:34:20","modified_gmt":"2025-10-24T14:34:20","slug":"smart-tv-tcl-75c655","status":"publish","type":"product","link":"https:\/\/dinaleo.com.ar\/sitio\/producto\/smart-tv-tcl-75c655\/","title":{"rendered":"Smart TV TCL 75C655"},"content":{"rendered":"<div class=\"ui-pdp-container__row ui-pdp-container__row--discrete-bar\">\n<div class=\"ui-vpp-highlighted-specs__discrete-bar\">\n<div class=\"ui-vpp-highlighted-specs__discrete-bar__attribute\">\n<p class=\"ui-pdp-family--REGULAR ui-vpp-highlighted-specs__discrete-bar__title\"><strong><span class=\"ui-pdp-color--BLACK ui-pdp-size--XSMALL ui-pdp-family--REGULAR\">Tama\u00f1o de la pantalla<\/span>:<\/strong> <span class=\"ui-pdp-color--BLACK ui-pdp-size--XSMALL ui-pdp-family--SEMIBOLD\">75 \u00bb <\/span>(<span class=\"ui-pdp-color--BLACK ui-pdp-size--XSMALL ui-pdp-family--REGULAR\">1.666 m x 7 cm x 95.8 cm<\/span>)<br \/>\n<strong><span class=\"ui-pdp-color--BLACK ui-pdp-size--XSMALL ui-pdp-family--REGULAR\">Resoluci\u00f3n:<\/span><\/strong> <span class=\"ui-pdp-color--BLACK ui-pdp-size--XSMALL ui-pdp-family--SEMIBOLD\">4K<br \/>\n<\/span><strong><span class=\"ui-pdp-color--BLACK ui-pdp-size--XSMALL ui-pdp-family--REGULAR\">Tipo de pantalla:<\/span><\/strong> <span class=\"ui-pdp-color--BLACK ui-pdp-size--XSMALL ui-pdp-family--SEMIBOLD\">QLED<br \/>\n<\/span><strong><span class=\"ui-pdp-color--BLACK ui-pdp-size--XSMALL ui-pdp-family--REGULAR\">Cantidad de puertos HDMI:<\/span><\/strong> <span class=\"ui-pdp-color--BLACK ui-pdp-size--XSMALL ui-pdp-family--SEMIBOLD\">3<br \/>\n<\/span><strong>Sistema operativo:<\/strong> Google TV<br \/>\n<strong>Con comando de voz integrado:<\/strong> S\u00ed<br \/>\n<strong>Cantidad de parlantes:<\/strong> 3<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"ui-pdp-container__row ui-pdp-container__row--technical-specifications\">\n<div class=\"ui-pdp-collapsable ui-vpp-highlighted-specs__striped-collapsed__action\">\n<div class=\"ui-pdp-collapsable__container\">\n<div class=\"ui-vpp-highlighted-specs__striped-specs\">\n<div class=\"ui-vpp-striped-specs\">\n<div class=\"ui-vpp-striped-specs__table\">\n<h3 class=\"ui-vpp-striped-specs__header\">Sonido<\/h3>\n<table class=\"andes-table\">\n<tbody class=\"andes-table__body\">\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Cantidad de parlantes<\/div>\n<\/th>\n<td id=\":R19f6lpakp7de:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R19f6lpakp7de:-value\" class=\"andes-table__column--value\">3<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Potencia m\u00e1xima de los parlantes<\/div>\n<\/th>\n<td id=\":R19n6lpakp7de:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R19n6lpakp7de:-value\" class=\"andes-table__column--value\">35 W<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div class=\"ui-vpp-striped-specs__table\">\n<h3 class=\"ui-vpp-striped-specs__header\">Especificaciones<\/h3>\n<table class=\"andes-table\">\n<tbody class=\"andes-table__body\">\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\"><\/th>\n<td id=\":R2if8lpakp7de:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\"><\/th>\n<td id=\":R2in8lpakp7de:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\"><\/th>\n<td id=\":R2iv8lpakp7de:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Con sistema de montaje VESA incorporado<\/div>\n<\/th>\n<td id=\":R2j78lpakp7de:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R2j78lpakp7de:-value\" class=\"andes-table__column--value\">S\u00ed<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Cantidad de n\u00facleos del procesador<\/div>\n<\/th>\n<td id=\":R2jf8lpakp7de:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R2jf8lpakp7de:-value\" class=\"andes-table__column--value\">4<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Capacidad de almacenamiento<\/div>\n<\/th>\n<td id=\":R2jn8lpakp7de:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R2jn8lpakp7de:-value\" class=\"andes-table__column--value\">32 GB<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div class=\"ui-vpp-striped-specs__table\">\n<h3 class=\"ui-vpp-striped-specs__header\">Peso y dimensiones<\/h3>\n<table class=\"andes-table\">\n<tbody class=\"andes-table__body\">\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Ancho x Profundidad x Altura<\/div>\n<\/th>\n<td id=\":R2ifalpakp7de:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R2ifalpakp7de:-value\" class=\"andes-table__column--value\">1.666 m x 7 cm x 95.8 cm<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Peso<\/div>\n<\/th>\n<td id=\":R2inalpakp7de:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R2inalpakp7de:-value\" class=\"andes-table__column--value\">24 kg<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Ancho con soporte<\/div>\n<\/th>\n<td id=\":R2ivalpakp7de:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R2ivalpakp7de:-value\" class=\"andes-table__column--value\">1,67 m<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Profundidad con soporte<\/div>\n<\/th>\n<td id=\":R2j7alpakp7de:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R2j7alpakp7de:-value\" class=\"andes-table__column--value\">34,3 cm<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Altura con soporte<\/div>\n<\/th>\n<td id=\":R2jfalpakp7de:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R2jfalpakp7de:-value\" class=\"andes-table__column--value\">1,03 m<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Peso con soporte<\/div>\n<\/th>\n<td id=\":R2jnalpakp7de:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R2jnalpakp7de:-value\" class=\"andes-table__column--value\">24,6 kg<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<h3 class=\"titulo-rojo\"><strong>LLEVALO EN 6 CUOTAS SIN INTER\u00c9S CON TODAS LAS TARJETAS<\/strong><\/h3>\n<p><strong>CONSULT\u00c1 POR TU CR\u00c9DITO <span class=\"titulo-rojo\">DINALEO!<\/span><\/strong><\/p>\n","protected":false},"featured_media":5018,"template":"","meta":[],"product_brand":[199],"product_cat":[154],"product_tag":[],"class_list":{"0":"post-5016","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-tcl","7":"product_cat-smart-tv-y-audio","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/product\/5016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/media\/5018"}],"wp:attachment":[{"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=5016"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/product_brand?post=5016"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/product_cat?post=5016"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/product_tag?post=5016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}