{"id":5202,"date":"2025-11-18T15:44:28","date_gmt":"2025-11-18T15:44:28","guid":{"rendered":"https:\/\/dinaleo.com.ar\/sitio\/?post_type=product&#038;p=5202"},"modified":"2025-11-18T15:44:29","modified_gmt":"2025-11-18T15:44:29","slug":"cafetera-atma-ca8182p","status":"publish","type":"product","link":"https:\/\/dinaleo.com.ar\/sitio\/producto\/cafetera-atma-ca8182p\/","title":{"rendered":"Cafetera Atma &#8211; CA8182P"},"content":{"rendered":"<div class=\"ui-pdp-container__row ui-pdp-container__row--highlighted-specs-title\">\n<h2 class=\"ui-vpp-text-alignment--left ui-pdp-color--BLACK ui-pdp-size--XLARGE ui-pdp-family--REGULAR highlighted-specs-title\">Caracter\u00edsticas del producto<\/h2>\n<\/div>\n<div class=\"ui-pdp-container__row ui-pdp-container__row--technical-specifications\">\n<div class=\"ui-pdp-collapsable ui-vpp-highlighted-specs__striped-collapsed__action\">\n<div class=\"ui-pdp-collapsable__container\">\n<div class=\"ui-vpp-highlighted-specs__striped-specs\">\n<div class=\"ui-vpp-striped-specs\">\n<div class=\"ui-vpp-striped-specs__table\">\n<h3 class=\"ui-vpp-striped-specs__header\">Caracter\u00edsticas principales<\/h3>\n<table class=\"andes-table\">\n<tbody class=\"andes-table__body\">\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Tipo de alimentaci\u00f3n<\/div>\n<\/th>\n<td id=\":Rkv2lpakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":Rkv2lpakp7te:-value\" class=\"andes-table__column--value\">Corriente el\u00e9ctrica<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div class=\"ui-vpp-striped-specs__table\">\n<h3 class=\"ui-vpp-striped-specs__header\">Especificaciones<\/h3>\n<table class=\"andes-table\">\n<tbody class=\"andes-table__body\">\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Tecnolog\u00eda<\/div>\n<\/th>\n<td id=\":R2if4lpakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R2if4lpakp7te:-value\" class=\"andes-table__column--value\">Autom\u00e1tica<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Capacidad de agua<\/div>\n<\/th>\n<td id=\":R2in4lpakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R2in4lpakp7te:-value\" class=\"andes-table__column--value\">1,8 L<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Potencia<\/div>\n<\/th>\n<td id=\":R2iv4lpakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R2iv4lpakp7te:-value\" class=\"andes-table__column--value\">1.000.000 W<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Tipos de filtros<\/div>\n<\/th>\n<td id=\":R2j74lpakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R2j74lpakp7te:-value\" class=\"andes-table__column--value\">Permanente<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div class=\"ui-vpp-striped-specs__table\">\n<h3 class=\"ui-vpp-striped-specs__header\">Dise\u00f1o<\/h3>\n<table class=\"andes-table\">\n<tbody class=\"andes-table__body\">\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Materiales de la estructura<\/div>\n<\/th>\n<td id=\":R19f6lpakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R19f6lpakp7te:-value\" class=\"andes-table__column--value\">Acero inoxidable<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Con pantalla digital<\/div>\n<\/th>\n<td id=\":R19n6lpakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R19n6lpakp7te:-value\" class=\"andes-table__column--value\">S\u00ed<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Con doble boquilla<\/div>\n<\/th>\n<td id=\":R19v6lpakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R19v6lpakp7te:-value\" class=\"andes-table__column--value\">No<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div class=\"ui-vpp-striped-specs__table\">\n<h3 class=\"ui-vpp-striped-specs__header\">Funciones<\/h3>\n<table class=\"andes-table\">\n<tbody class=\"andes-table__body\">\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Incluye temporizador<\/div>\n<\/th>\n<td id=\":R2if8lpakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R2if8lpakp7te:-value\" class=\"andes-table__column--value\">S\u00ed<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Con emisi\u00f3n de vapor<\/div>\n<\/th>\n<td id=\":R2in8lpakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R2in8lpakp7te:-value\" class=\"andes-table__column--value\">No<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Con dispositivo de antigoteo<\/div>\n<\/th>\n<td id=\":R2iv8lpakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R2iv8lpakp7te:-value\" class=\"andes-table__column--value\">S\u00ed<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Con funci\u00f3n de calentamiento de tazas<\/div>\n<\/th>\n<td id=\":R2j78lpakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R2j78lpakp7te:-value\" class=\"andes-table__column--value\">No<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Con indicador de agua<\/div>\n<\/th>\n<td id=\":R2jf8lpakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R2jf8lpakp7te:-value\" class=\"andes-table__column--value\">S\u00ed<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Con limpieza autom\u00e1tica<\/div>\n<\/th>\n<td id=\":R2jn8lpakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R2jn8lpakp7te:-value\" class=\"andes-table__column--value\">No<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<div class=\"ui-vpp-striped-specs\">\n<div class=\"ui-vpp-striped-specs__table\">\n<h3 class=\"ui-vpp-striped-specs__header\">Caracter\u00edsticas generales<\/h3>\n<table class=\"andes-table\">\n<tbody class=\"andes-table__body\">\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Marca<\/div>\n<\/th>\n<td id=\":R54f35pakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R54f35pakp7te:-value\" class=\"andes-table__column--value\">Atma<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">L\u00ednea<\/div>\n<\/th>\n<td id=\":R54n35pakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R54n35pakp7te:-value\" class=\"andes-table__column--value\">De Filtro<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Modelo<\/div>\n<\/th>\n<td id=\":R54v35pakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R54v35pakp7te:-value\" class=\"andes-table__column--value\">Ca8182p<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Modelo alfanum\u00e9rico<\/div>\n<\/th>\n<td id=\":R55735pakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R55735pakp7te:-value\" class=\"andes-table__column--value\">94CA8182P<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Color<\/div>\n<\/th>\n<td id=\":R55f35pakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R55f35pakp7te:-value\" class=\"andes-table__column--value\">Negro<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Voltaje<\/div>\n<\/th>\n<td id=\":R55n35pakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R55n35pakp7te:-value\" class=\"andes-table__column--value\">220V<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Tipos de cafetera<\/div>\n<\/th>\n<td id=\":R55v35pakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R55v35pakp7te:-value\" class=\"andes-table__column--value\">De filtro<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Es port\u00e1til<\/div>\n<\/th>\n<td id=\":R56735pakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R56735pakp7te:-value\" class=\"andes-table__column--value\">No<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Es empotrable<\/div>\n<\/th>\n<td id=\":R56f35pakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R56f35pakp7te:-value\" class=\"andes-table__column--value\">No<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div class=\"ui-vpp-striped-specs__table\">\n<h3 class=\"ui-vpp-striped-specs__header\">Accesorios<\/h3>\n<table class=\"andes-table\">\n<tbody class=\"andes-table__body\">\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Incluye bandeja recolectora removible<\/div>\n<\/th>\n<td id=\":Rkv55pakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":Rkv55pakp7te:-value\" class=\"andes-table__column--value\">S\u00ed<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div class=\"ui-vpp-striped-specs__table\">\n<h3 class=\"ui-vpp-striped-specs__header\">Peso y dimensiones<\/h3>\n<table class=\"andes-table\">\n<tbody class=\"andes-table__body\">\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Ancho<\/div>\n<\/th>\n<td id=\":R19f75pakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R19f75pakp7te:-value\" class=\"andes-table__column--value\">22,5 cm<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Profundidad<\/div>\n<\/th>\n<td id=\":R19n75pakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R19n75pakp7te:-value\" class=\"andes-table__column--value\">17,8 cm<\/span><\/td>\n<\/tr>\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Altura<\/div>\n<\/th>\n<td id=\":R19v75pakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":R19v75pakp7te:-value\" class=\"andes-table__column--value\">31,5 cm<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<div class=\"ui-vpp-striped-specs__table\">\n<h3 class=\"ui-vpp-striped-specs__header\">Otros<\/h3>\n<table class=\"andes-table\">\n<tbody class=\"andes-table__body\">\n<tr class=\"andes-table__row ui-vpp-striped-specs__row\">\n<th class=\"andes-table__header andes-table__header--left ui-vpp-striped-specs__row__column ui-vpp-striped-specs__row__column--id\" scope=\"row\">\n<div class=\"andes-table__header__container\">Incluye pilas<\/div>\n<\/th>\n<td id=\":Rkv95pakp7te:\" class=\"andes-table__column andes-table__column--left andes-table__column--vertical-align-center ui-vpp-striped-specs__row__column\"><span id=\":Rkv95pakp7te:-value\" class=\"andes-table__column--value\">No<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<h3 class=\"titulo-rojo\"><strong>LLEVALO EN 6 CUOTAS SIN INTER\u00c9S CON TODAS LAS TARJETAS<\/strong><\/h3>\n<p>       <strong>CONSULT\u00c1 POR TU CR\u00c9DITO PERSONAL <span class=\"titulo-rojo\">DINALEO!<\/span><\/strong><\/p>\n<p>ABONANDO EN EFECTIVO, D\u00c9BITO O TRANSFERENCIA 15% DE DESCUENTO <\/p>\n","protected":false},"featured_media":5203,"template":"","meta":[],"product_brand":[181],"product_cat":[166],"product_tag":[],"class_list":{"0":"post-5202","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-atma","7":"product_cat-pequenos-electrodomesticos","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/product\/5202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/media\/5203"}],"wp:attachment":[{"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=5202"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/product_brand?post=5202"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/product_cat?post=5202"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/product_tag?post=5202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}