{"id":5324,"date":"2026-03-04T22:03:39","date_gmt":"2026-03-04T22:03:39","guid":{"rendered":"https:\/\/dinaleo.com.ar\/sitio\/?post_type=product&#038;p=5324"},"modified":"2026-03-04T22:03:39","modified_gmt":"2026-03-04T22:03:39","slug":"heladera-philco-phct260x-260lts-gris","status":"publish","type":"product","link":"https:\/\/dinaleo.com.ar\/sitio\/producto\/heladera-philco-phct260x-260lts-gris\/","title":{"rendered":"Heladera Philco PHCT260X -260LTS (Gris)"},"content":{"rendered":"<h3 data-start=\"86\" data-end=\"477\">DESCRIPCI\u00d3N:<\/h3>\n<p data-start=\"86\" data-end=\"477\">La heladera Philco PHCT260x es la combinaci\u00f3n perfecta de capacidad, eficiencia y dise\u00f1o moderno. Con 260 litros de almacenamiento y un pr\u00e1ctico freezer superior, se adapta a las necesidades de cualquier hogar, garantizando una conservaci\u00f3n \u00f3ptima de tus alimentos. Su clasificaci\u00f3n de eficiencia energ\u00e9tica A permite un consumo reducido sin comprometer el rendimiento.<\/p>\n<h3 data-start=\"86\" data-end=\"477\">Caracter\u00edsticas:<\/h3>\n<p data-start=\"479\" data-end=\"516\">Dise\u00f1o Funcional y Vers\u00e1til<\/p>\n<p data-start=\"517\" data-end=\"732\">Freezer superior, para un acceso r\u00e1pido a tus congelados.<br data-start=\"580\" data-end=\"583\" \/>Puertas reversibles, que se adaptan a cualquier espacio de tu cocina.<br data-start=\"658\" data-end=\"661\" \/>\u00a0Manijas embutidas, para una est\u00e9tica moderna y c\u00f3moda apertura.<\/p>\n<p data-start=\"734\" data-end=\"763\">Conservaci\u00f3n \u00d3ptima<\/p>\n<p data-start=\"764\" data-end=\"1163\">\u00a0Sistema de fr\u00edo c\u00edclico, mantiene la humedad natural de los alimentos y evita la resequedad.<br data-start=\"862\" data-end=\"865\" \/>\u00a0Control de temperatura regulable, para adaptar la potencia seg\u00fan la cantidad de productos almacenados.<br data-start=\"973\" data-end=\"976\" \/>\u00a0Estantes de vidrio templado ajustables, brindan mayor resistencia y flexibilidad.<br data-start=\"1063\" data-end=\"1066\" \/>\u00a04 anaqueles en la puerta, ideales para almacenar botellas y envases de distintos tama\u00f1os.<\/p>\n<p data-start=\"1165\" data-end=\"1213\">Eficiencia y Cuidado del Medioambiente<\/p>\n<p data-start=\"1214\" data-end=\"1355\">\u00a0Gas R600a, un refrigerante ecol\u00f3gico que protege la capa de ozono.<br data-start=\"1286\" data-end=\"1289\" \/>\u00a0Bajo consumo energ\u00e9tico, gracias a su clasificaci\u00f3n A.<\/p>\n","protected":false},"excerpt":{"rendered":"<h3 class=\"titulo-rojo\"><strong>LLEVALO EN 6 CUOTAS SIN INTER\u00c9S CON TODAS LAS TARJETAS<\/strong><\/h3>\n<p><strong>CONSULT\u00c1 POR TU CR\u00c9DITO <span class=\"titulo-rojo\">DINALEO!<\/span><\/strong><\/p>\n","protected":false},"featured_media":5325,"template":"","meta":[],"product_brand":[176],"product_cat":[156],"product_tag":[],"class_list":{"0":"post-5324","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-philco","7":"product_cat-heladeras-freezers","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/product\/5324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/media\/5325"}],"wp:attachment":[{"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=5324"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/product_brand?post=5324"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/product_cat?post=5324"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/product_tag?post=5324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}