{"id":5343,"date":"2026-03-10T13:09:46","date_gmt":"2026-03-10T13:09:46","guid":{"rendered":"https:\/\/dinaleo.com.ar\/sitio\/?post_type=product&#038;p=5343"},"modified":"2026-03-10T13:09:46","modified_gmt":"2026-03-10T13:09:46","slug":"freezer-gafa-fghi100b-s-117lts","status":"publish","type":"product","link":"https:\/\/dinaleo.com.ar\/sitio\/producto\/freezer-gafa-fghi100b-s-117lts\/","title":{"rendered":"Freezer Gafa fghi100b-s  -117lts"},"content":{"rendered":"<h3>Descripci\u00f3n:<\/h3>\n<p>Conserva alimentos, bebidas y envases de cualquier tama\u00f1o de manera pr\u00e1ctica y organizada con el freezer Gafa FGHI100B-S Blanco, que cuenta con un motor de tecnolog\u00eda inverter y 10 a\u00f1os de garant\u00eda para mantener una temperatura estable y \u00f3ptima para la preservaci\u00f3n de tus alimentos. Esta tecnolog\u00eda tambi\u00e9n te permite ahorrar hasta un 6% de energ\u00eda, con un funcionamiento m\u00e1s silencioso.<\/p>\n<h3>Caracter\u00edsticas:<\/h3>\n<p>Tecnolog\u00eda Inverter: Asegura una temperatura estable para la conservaci\u00f3n de alimentos y ahorra hasta un 6% de energ\u00eda, con motor m\u00e1s silencioso y 10 a\u00f1os de garant\u00eda.<\/p>\n<p>Clasificaci\u00f3n Energ\u00e9tica A: Menor consumo de energ\u00eda y mayor eficiencia.<\/p>\n<p>4 Temperaturas: Elige entre las opciones de Freezer, Turno, Conservador y Enfriador seg\u00fan tus necesidades.<\/p>\n<p>Gas Ecol\u00f3gico: Contribuye al cuidado del medioambiente y de la capa de ozono.<\/p>\n<p>F\u00e1cil Limpieza: Descongela tu freezer con mayor facilidad gracias al desagote frontal.<\/p>\n<p>Gran Capacidad: Almacena y organiza alimentos y bebidas en sus 117L de espacio interior.<\/p>\n<p>Canasto Interno: Ofrece flexibilidad y facilita la organizaci\u00f3n del espacio.<\/p>\n<p>Ruedas 360\u00ba: Permite un desplazamiento c\u00f3modo y pr\u00e1ctico.<\/p>\n<p>Manija Ergon\u00f3mica: Dise\u00f1ada para facilitar la apertura del freezer.<\/p>\n","protected":false},"excerpt":{"rendered":"<h3 class=\"titulo-rojo\"><strong>LLEVALO EN 6 CUOTAS SIN INTER\u00c9S CON TODAS LAS TARJETAS<\/strong><\/h3>\n<p><strong>CONSULT\u00c1 POR TU CR\u00c9DITO <span class=\"titulo-rojo\">DINALEO!<\/span><\/strong><\/p>\n","protected":false},"featured_media":5347,"template":"","meta":[],"product_brand":[175],"product_cat":[156],"product_tag":[],"class_list":{"0":"post-5343","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-gafa","7":"product_cat-heladeras-freezers","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/product\/5343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/media\/5347"}],"wp:attachment":[{"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/media?parent=5343"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/product_brand?post=5343"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/product_cat?post=5343"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dinaleo.com.ar\/sitio\/wp-json\/wp\/v2\/product_tag?post=5343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}